{"id":121,"date":"2023-02-06T19:16:38","date_gmt":"2023-02-06T19:16:38","guid":{"rendered":"http:\/\/pingeon.com\/?p=121"},"modified":"2023-02-06T19:29:11","modified_gmt":"2023-02-06T19:29:11","slug":"planchers-et-parquets","status":"publish","type":"post","link":"https:\/\/pingeon.com\/index.php\/2023\/02\/06\/planchers-et-parquets\/","title":{"rendered":"Planchers et parquets"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbContact Form Section\u00a0\u00bb module_id=\u00a0\u00bbrsvp\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; background_color=\u00a0\u00bb#d1af83&Prime; background_blend=\u00a0\u00bbcolor\u00a0\u00bb custom_padding=\u00a0\u00bb33px||120px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_row admin_label=\u00a0\u00bbContact Form Title\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text admin_label=\u00a0\u00bbSubtitle\u00a0\u00bb _builder_version=\u00a0\u00bb4.19.5&Prime; text_font=\u00a0\u00bbOpen Sans||||\u00a0\u00bb text_font_size=\u00a0\u00bb17px\u00a0\u00bb text_line_height=\u00a0\u00bb1.9em\u00a0\u00bb background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb background_layout=\u00a0\u00bbdark\u00a0\u00bb max_width=\u00a0\u00bb800px\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb|||\u00a0\u00bb custom_padding=\u00a0\u00bb|||\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\">A<a name=\"top\" style=\"color: #ffffff;\"><\/a><b><span style=\"font-size: medium;\"><\/span><\/b><b><span style=\"font-size: medium;\">u moyen \u00e2ge \u00e0 la fin du seizi\u00e8me si\u00e8cle, dans les pi\u00e8ces o\u00f9 les habitants vivent avec leurs animaux familiers, les sols doivent pouvoir \u00eatre lav\u00e9s \u00e0 grande eau. Aussi les grandes salles vo\u00fbt\u00e9es des ch\u00e2teaux (salle des gardes, salles des festins ou \u00ab\u00a0grand tinel\u00a0\u00bb), sont-elles g\u00e9n\u00e9ralement dall\u00e9es de pierre.A<\/span><\/b><b><span style=\"font-size: medium;\">Les planchers de bois sont r\u00e9serv\u00e9s aux estrades ou marchepieds, plac\u00e9s sous les chaises d&rsquo;honneur, marque de rang social, sous les lits, voire sous les si\u00e8ges et les tables des festins hivernaux. Ils sont souvent recouverts d&rsquo;un tapis velu.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Puis, petit \u00e0 petit, le sol des \u00e9tages sup\u00e9rieurs des maisons, en carreaux de terre cuite, se transforme en plancher.<br \/>Compos\u00e9s de planches juxtapos\u00e9es \u00e0 joints vifs ou \u00e0 feuillures. Refendus \u00e0 la largeur de 5 ou 7 pouces (1) les planchers sont fix\u00e9s sur les solives par des clous forg\u00e9s apparents. Ceci jusqu&rsquo;au milieu du dix-septi\u00e8me si\u00e8cle.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Parall\u00e8lement, est arriv\u00e9 le plancher assembl\u00e9 par rainure et languette avec des lames de 3 \u00e0 4 pouces. Il est pos\u00e9 \u00ab\u00a0\u00e0 l&rsquo;anglaise\u00a0\u00bb, c&rsquo;est \u00e0 dire que les lames sont de toutes longueurs, les clous deviennent invisibles.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">A partir du d\u00e9but du dix-septi\u00e8me si\u00e8cle, on commence \u00e0 trouver des lames de plancher dispos\u00e9es selon diff\u00e9rents motifs:<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">&#8211; Le plancher en plusieurs trav\u00e9es, form\u00e9es de planchers de 5 \u00e0 6 pieds de long au bout desquelles on met une frise en sens contraire (gravure \u00ab\u00a0les vierges folles de le Blond \u00e0 Paris, 1640, British Museum), &#8211; Le plancher \u00e0 point de Hongrie, fait d&rsquo;alaises de 3 \u00e0 4 pieds de long et de 3 \u00e0 7 pouces de large, sa coupe en bout est faite en onglet (45\u00b0). La largeur de chaque trav\u00e9e est de 25 \u00e0 34 pouces, elle sont d&rsquo;un nombre impair de fa\u00e7on \u00e0 ce qu&rsquo;il se trouve un joint au milieu de la pi\u00e8ce.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Dans les appartements pour des raisons thermiques et acoustiques, on pr\u00e9f\u00e8re de plus en plus les planchers de bois auxquels on donne le nom de parquets lorsque plusieurs planches sont assembl\u00e9es entre elles pour former une \u00ab\u00a0feuille\u00a0\u00bb. (le mot parquet venant de parc, enclos entourant l&rsquo;estrade, d&rsquo;o\u00f9 se rend la justice).<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Les planchers d&rsquo;assemblage ou parquets sont g\u00e9n\u00e9ralement constitu\u00e9s par des feuilles de parquet compos\u00e9es de lattes de bois de ch\u00eane, assembl\u00e9es, cir\u00e9es, qui ont depuis deux pieds (2) jusqu&rsquo;\u00e0 quatre pieds de c\u00f4t\u00e9 mais celle de trois pieds \u00e0 trois pieds un quart sont les plus usit\u00e9es, et dont les compartiments sont dispos\u00e9s, soit \u00e0 l&rsquo;\u00e9querre par rapport au b\u00e2ti (dit aujourd&rsquo;hui parquet de Chantilly), soit en diagonale (dit aujourd&rsquo;hui parquet de Versailles).<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Leur \u00e9paisseur varie de trois quarts de pouce \u00e0 un pouce et demi et va jusqu&rsquo;\u00e0 deux pouces pour les rez-de-chauss\u00e9e tr\u00e8s humides.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Elles sont fix\u00e9es sur des lambourdes pos\u00e9es en diagonale. Ces lambourdes sont au nombre de 5 pour les grandes feuilles et de 3 pour les petites.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Elle supportent toujours les pointes des feuilles. Elles sont elles-m\u00eames clou\u00e9es sur les solives, parfois un sous-plancher suppl\u00e9mentaire s&rsquo;intercale pour plus de r\u00e9sistance.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Chaque feuille peut \u00eatre s\u00e9par\u00e9e de sa voisine par une frise d&rsquo;encadrement (de 3 \u00e0 4 pouces de large) ou simplement juxtapos\u00e9e.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Quant \u00e0 la disposition g\u00e9n\u00e9rale du parquet, elle se fait des deux mani\u00e8res suivantes: l&rsquo;une est de mettre les c\u00f4t\u00e9s des feuilles parall\u00e8les \u00e0 ceux de la pi\u00e8ce, l&rsquo;autre est de mettre la diagonale parall\u00e8le \u00e0 ces derniers.<br \/>L&rsquo;ensemble pouvant comporter, ou non, suivant le cas une frise sur le pourtour de la pi\u00e8ce, tout au long des murs.<br \/>Par contre, la \u00ab\u00a0pierre foy\u00e8re\u00a0\u00bb ou devant de chemin\u00e9e, est toujours entour\u00e9e d&rsquo;une frise. Pour les pi\u00e8ces de parade, ou de grande qualit\u00e9, les feuilles seront d&rsquo;une grandeur relative \u00e0 celle de la pi\u00e8ce, faisant que l&rsquo;on trouve un nombre complet de feuilles dans chaque pi\u00e8ce, de sorte qu&rsquo;il n&rsquo;y ait que des feuilles ou des demi feuilles, \u00ab\u00a0ce qui donne beaucoup de magnificence et de grandeur \u00e0 l&rsquo;appartement\u00a0\u00bb.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Ces parquets peuvent aussi comporter une marqueterie massive (appel\u00e9s alors parquet de marqueterie ou parquet en mosa\u00efque) compos\u00e9 de motifs en \u00e9toile, par exemple, comme au ch\u00e2teau de Maisons. Dans ce m\u00eame ch\u00e2teau il subsiste un parquet de marqueterie de bois de rapport, dans le cabinet des Miroirs.<br \/>Un autre parquet de bois pr\u00e9cieux existait encore il y a peu au ch\u00e2teau de Fl\u00e9ch\u00e8res (Ain).<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Sur une gravure d&rsquo;Abraham Bosse repr\u00e9sentant la chambre du Roi \u00e0 Fontainebleau en 1645, on voit un parquet \u00e0 compartiments carr\u00e9s d\u00e9cor\u00e9s de l&rsquo;initiale royale couronn\u00e9e, alternant avec de grandes fleurs de lys de bois de rapport.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Nicod\u00e8me Tessin \u00e9crit en 1693 : \u00a0\u00bb A Trianon &#8230; les parquets touchent aux lambris. Il n&rsquo;y a qu&rsquo;une seule pi\u00e8ce \u00e0 Versailles dont le parquet soit par carr\u00e9s&#8230; tout le reste est en losange \u00e0 la nouvelle mani\u00e8re\u00a0\u00bb.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">R\u00e9serv\u00e9s aux petites surfaces des cabinets et des estrades, les parquets en mosa\u00efque sont aussi employ\u00e9s dans les alc\u00f4ves, nous apprend le Mercure Galant de 1673: \u00a0\u00bb Les gens de qualit\u00e9 ne veulent plus de tapis de pied dans leurs alc\u00f4ves, \u00e0 cause de la poudre (poussi\u00e8re) qu&rsquo;ils conservent, c&rsquo;est pourquoi, il les font parqueter de bois de diverses couleurs\u00a0\u00bb.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Rien ne subsiste de ces somptueuses mosa\u00efques de bois pr\u00e9cieux incrust\u00e9s, oeuvre de Jean Mac\u00e9 (mort en 1672), qui orn\u00e8rent les estrades et certains planchers des cabinets du Louvre (cabinet de la reine m\u00e8re vers 1665), des Tuileries, de Saint-Germain, de Fontainebleau et de Versailles. Le parquet du cabinet des M\u00e9dailles est fait par Pierre Poitou aux Gobelins en 1685, ceux des cabinets du Dauphin sont l&rsquo;oeuvre d&rsquo;Andr\u00e9-Charles Boulle en 1683.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Un portrait du Grand Cond\u00e9 (vers 1660) \u00e0 Chantilly (Collection Jones, Victoria et Albert Museum &#8211; Londres) et quelques rares dessins nous en r\u00e9v\u00e8lent l&rsquo;aspect chatoyant, comme celui de la Petite Galerie de Versailles (1686) oeuvre d&rsquo;Alexandre Jean Oppenhordt (B.N. Estampes).<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Cependant un exemple plus simple est encore conserv\u00e9 dans le cabinet dor\u00e9 de l&rsquo;h\u00f4tel de Brancas \u00e0 Paris. Un fragment d&rsquo;une estrade royale en marqueterie d&rsquo;\u00e9caille et de cuivre a peut-\u00eatre \u00e9t\u00e9 remploy\u00e9 par Etienne Levasseur (1721-1800) dans un secr\u00e9taire appartenant \u00e0 la reine d&rsquo;Angleterre.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Au dix-huiti\u00e8me si\u00e8cle, comme au si\u00e8cle pr\u00e9c\u00e9dent les planchers des appartements sont constitu\u00e9s par des panneaux de parquets d&rsquo;assemblage carr\u00e9s de bois de ch\u00eane cir\u00e9, dont les compartiments sont pos\u00e9s soit \u00e0 l&rsquo;\u00e9querre, soit en diagonale, avec ou sans frise.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Des dessins g\u00e9om\u00e9triques peuvent en varier l&rsquo;aspect, tel le parquet de l&rsquo;h\u00e9micycle de la Salle du Conseil \u00e0 Fontainebleau, orn\u00e9 d&rsquo;une \u00e9toile par Gabriel. En g\u00e9n\u00e9ral, les parquets cir\u00e9s et miroitants restent nus, sans tapis. Ils sont entretenus par les indispensables frotteurs.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">A l&rsquo;h\u00f4tel Choiseul \u00e0 Paris, il existait des parquets de mosa\u00efque de bois de rapport, ainsi qu&rsquo;on peut le voir sur les gouaches d&rsquo;Henri Van Blarenberghe (1734-1812) ornant la \u00ab\u00a0bo\u00eete Choiseul\u00a0\u00bb. D&rsquo;autre part, il semble qu&rsquo;\u00e0 l&rsquo;h\u00f4tel de Soubise, les salons ovales aient eu des \u00ab\u00a0parquets de bois vari\u00e9s avec des ornements et des compartiments tr\u00e8s ing\u00e9nieux\u00a0\u00bb. On sait que des ateliers dans la mouvance de l&rsquo;\u00e9b\u00e9niste Hache fils \u00e0 Grenoble, produisaient encore des feuilles de parquets compos\u00e9s de diff\u00e9rents bois vers la fin du dix-huiti\u00e8me si\u00e8cle.<br \/>Dans les \u00e9tages r\u00e9serv\u00e9s au service, le sol des chambres et des couloirs est garni de carreaux de terre cuite (tommettes) \u00e0 six pans de quatre pouces (10.8 cm) que l&rsquo;on cire.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">(1) 1 pouce fran\u00e7ais = 27,0696 mm<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Comme dans le \u00ab\u00a0cabinet de deuil\u00a0\u00bb au ch\u00e2teau de Ch\u00e2teaudun, qui a aussi conserv\u00e9 des boiseries tr\u00e8s simples dans l&rsquo;ancien charretier. L&rsquo;usage en continuera au seizi\u00e8me si\u00e8cle, comme on peut le voir au ch\u00e2teau de Blois, dans le cabinet de la Reine Catherine de M\u00e9dicis (1519-1589), et au ch\u00e2teau de Beauregard, dans le Loir-et-Cher, au cabinet des grelots, qui sont enti\u00e8rement bois\u00e9s, ou celui du ch\u00e2teau de Pibriac (Haute-Garonne).<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Les boiseries, dites \u00ab\u00a0chambrillage\u00a0\u00bb ont pour but d&rsquo;assurer une isolation thermique au bas des murs de pierre au-dessous des tapisseries mobiles murales. Celles qui datent du quinzi\u00e8me si\u00e8cle ont aujourd&rsquo;hui presque disparu, sauf quelques vestiges tels les boiseries provenant d&rsquo;une maison de la r\u00e9gion du Mans (Sarthe) et qui sont au Mus\u00e9e de Philadelphie.<br \/>Faits de planches \u00e9troites de un pied (2) d\u00e9bit\u00e9es \u00e0 la scie \u00e0 eau, invent\u00e9e en 1322 \u00e0 Augsbourg. Assembl\u00e9s \u00e0 tenons-mortaises et chevill\u00e9s, ces panneaux peuvent \u00eatre orn\u00e9s de sculptures en bas-relief de motifs de \u00ab\u00a0remplages\u00a0\u00bb ou de \u00ab\u00a0plis de serviettes\u00a0\u00bb.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Les peintures de l&rsquo;\u00e9poque telle l&rsquo;Annonciation par G\u00e9rard DAVID (1460-1523), nous repr\u00e9sentent souvent des boiseries avec des si\u00e8ges incorpor\u00e9s, tels des stalles comme celles provenant du ch\u00e2teau de Villeneuve-Lembron, aujourd&rsquo;hui conserv\u00e9s au Mus\u00e9e des Arts D\u00e9coratifs.<br \/>Concurremment au d\u00e9cor mobile des tapisseries, on trouve des murs enti\u00e8rement rev\u00eatus de boiserie, mais ce d\u00e9cor immuable est \u00ab\u00a0plus co\u00fbteux\u00a0\u00bb. Inspir\u00e9s peut-\u00eatre par les dosserets des stalles et les boiseries des chapelles.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">A partir du seizi\u00e8me si\u00e8cle, les vantaux des portes s&rsquo;encadrent dans les boiserie dites \u00ab\u00a0\u00e0 la fran\u00e7aise\u00a0\u00bb, c&rsquo;est \u00e0 dire \u00ab\u00a0\u00e0 hauteur de bras lev\u00e9\u00a0\u00bb (sept \u00e0 huit pieds environ) pour pouvoir s&rsquo;ins\u00e9rer dans une boiserie continue constitu\u00e9e de petits panneaux \u00e9troits sculpt\u00e9s ou peints. Le d\u00e9cor de serviettes de la p\u00e9riode pr\u00e9c\u00e9dente est remplac\u00e9 par des motifs verticaux.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Les boiserie aux panneaux simplement \u00e9tag\u00e9s sont proportionnelles \u00e0 la largeur des planches d\u00e9bit\u00e9es par les scieurs de long. Ceux des boiseries basses de la chambre de parade d&rsquo;Henri II au Louvre (1559), sont de forme carr\u00e9e, orn\u00e9s de troph\u00e9es d&rsquo;armes antiques, sculpt\u00e9s et dor\u00e9s.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Si les exemples de boiseries ant\u00e9rieures \u00e0 Mazarin ne nous sont parvenus que d\u00e9pec\u00e9es et arbitrairement dispos\u00e9es (boiserie de l&rsquo;h\u00f4tel de Bullion 1634 \u00e0 Paris; boiserie de la chambre et du cabinet de la Mar\u00e9chale de La Meilleraye, \u00e0 l&rsquo;Arsenal 1637), on en trouve encore, soigneusement remont\u00e9es comme celles du ch\u00e2teau de Chenailles (Loiret), d\u00e9cor\u00e9 entre 1610 et 1620, et qui sont au mus\u00e9e de Cleveland (Etat-Unis), ou encore in situ dans le ch\u00e2teau de Cormatin (Sa\u00f4ne et Loire), au cabinet des Vertus au ch\u00e2teau d&rsquo;Oiron, au cabinet des Muses (vers 1635); au ch\u00e2teau d&rsquo;Ancy-le-Franc (cabinet du Pastor Fido).<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Les boiserie \u00ab\u00a0\u00e0 hauteur de bras lev\u00e9\u00a0\u00bb, dont le sommet des panneaux continue la ligne des portes, sont rehauss\u00e9es de dorures et divis\u00e9es verticalement en trois parties: boiserie basse, boiserie d&rsquo;\u00e9tage et attique. Du parquet au plafond, on trouve: une plinthe peinte en faux marbre, pour effectuer la transition entre le parquet de ch\u00eane naturel et la boiserie et aussi pour dissimuler les marques des coups de balai; un soubassement d\u00e9cor\u00e9 en peinture de bas-reliefs peints en grisaille, d\u00e9nomm\u00e9 \u00ab\u00a0basse taille\u00a0\u00bb ou des natures mortes de fleurs et de fruits, en trompe l&rsquo;oeil, somm\u00e9 d&rsquo;une cimaise l\u00e9g\u00e8rement saillante. Ce sont les boiseries d&rsquo;appui qui r\u00e8gnent avec les all\u00e8ges des fen\u00eatres.<br \/>Au-dessus on trouve les boiseries d&rsquo;\u00e9tage, ou boiseries \u00e0 demi-rev\u00eatement, compos\u00e9es de panneaux verticaux d\u00e9cor\u00e9s de paysages, de vases de fleurs ou de grotesques, orn\u00e9s de guirlandes, supportant un entablement saillant (astragale) sur lequel on peut poser des vases de fa\u00efence (Chenailles) \u00e0 moins que ceux-ci ne soient peints en trompe l&rsquo;oeil, comme dans un cabinet du ch\u00e2teau de Saint-Marcel de F\u00e9line (Loire) 1661; enfin entre l&rsquo;entablement et la corniche, l&rsquo;attique, orn\u00e9 de peintures sur toile souvent s\u00e9par\u00e9es par des montants peints et sculpt\u00e9s. Les peintures narratives ont pour sujet la mythologie (ch\u00e2teau de Cormatin, H\u00f4tel Lambert, dans les cabinets de l&rsquo;Amour, des Muses et des Bains (1643-1644), Arsenal dans le cabinet des Femmes Fortes), ainsi que l&rsquo;histoire et les cycles romanesques \u00e0 la mode: le Roland furieux, la J\u00e9rusalem d\u00e9livr\u00e9e, le Pastor Fido, l&rsquo;Aminte.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Les d\u00e9vots refusent toutefois d&rsquo;avoir chez eux des peintures \u00e0 sujets mythologiques, qu&rsquo;ils jugent pa\u00efennes, et ils commandent des tableaux illustrant des sc\u00e8nes de l&rsquo;Ancien Testament, celles du nouveau \u00e9tant r\u00e9serv\u00e9es aux \u00e9glises et aux couvents.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Dans les grandes pi\u00e8ces, outre les boiseries d&rsquo;appui surmont\u00e9es de tapisseries, on trouve des parois enti\u00e8rement bois\u00e9es; \u00e0 Fontainebleau \u00e0 l&rsquo;exemple de la galerie et de la Salle de Bal, le grand cabinet d&rsquo;Henri IV \u00e0 un haut soubassement de boiseries moulur\u00e9es distribu\u00e9es avec sym\u00e9trie, mais avec plus de libert\u00e9 vis-\u00e0-vis de l&rsquo;Antiquit\u00e9 et des Ordres. Ces boiseries sont surmont\u00e9es de grandes peintures sur toile narrant l&rsquo;histoire de Th\u00e9ag\u00e8ne et Charicl\u00e9e, par Amboise Dubois.<br \/>Certaines boiseries de Fontainebleau sont peintes en ocre rouge fonc\u00e9 ou en blanc et la d\u00e9coration de paysages et de sc\u00e8nes antiques qui les ornent est associ\u00e9e \u00e0 \u00ab\u00a0des vases, des chiffres, ou des ornements l\u00e9gers\u00a0\u00bb ainsi que le souligne Jean-Pierre Samoyault.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">D&rsquo;autres grandes pi\u00e8ces sont bient\u00f4t d\u00e9cor\u00e9es d&rsquo;un quadrillage de boiseries sur toute la hauteur des parois; au-dessus de la boiserie d&rsquo;appui qui joue le r\u00f4le du stylobate, des panneaux \u00e9troits tiennent lieu de pilastres et s\u00e9parent des panneaux r\u00e9guliers \u00e0 grands cadres, au trac\u00e9 rectiligne montant jusqu&rsquo;\u00e0 la frise sous la corniche, comme \u00e0 Sully-Sur-Loire et \u00e0 Villebon (Essonne) (1620) o\u00f9 ils sont peints en faux bois ainsi que les \u00ab\u00a0portes \u00e0 placards\u00a0\u00bb plac\u00e9es en enfilade le long de la fa\u00e7ade et souvent de mani\u00e8re sym\u00e9trique vers le fond (1650). Au ch\u00e2teau de Maisons, sur les dessus de portes du salon \u00e0 l&rsquo;italienne, des vases de Chine peints en trompe l&rsquo;oeil succ\u00e8dent \u00e0 l&#8217;emploi de porcelaines v\u00e9ritables pos\u00e9es sur les chambranles saillants.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">A d\u00e9faut des fastueux appartements de Mazarin, disparus \u00e0 l&rsquo;exception de la galerie, nous pouvons nous en faire une id\u00e9e en voyant les d\u00e9cors ex\u00e9cut\u00e9s au milieu du si\u00e8cle dans l&rsquo;appartement de la reine m\u00e8re \u00e0 Fontainebleau et dans un certain nombre d&rsquo;h\u00f4tels parisiens. A l&rsquo;h\u00f4tel Lambert , dans la chambre de la Pr\u00e9sidente, les doubles portes sym\u00e9triques des deux enfilades et qui sont aussi pr\u00e9cieusement orn\u00e9es que les boiseries peintes de grotesques inspir\u00e9s de Rapha\u00ebl, se d\u00e9tachent sur un fond de dorure que l&rsquo;on retrouve sur les poutres du plafond, encadrant les toiles d&rsquo;Eustache Le Sueur (1615-1655).<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Mais c&rsquo;est \u00e0 Vaux-le-Vicomte qu&rsquo;on voit le plus bel ensemble des d\u00e9cors de \u00ab\u00a0style Mazarin\u00a0\u00bb ou, plut\u00f4t ne faudrait-il pas parler de \u00ab\u00a0style Fouquet\u00a0\u00bb ?<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Cependant, on peut penser que c&rsquo;est au jeune Charles Le Brun, qu&rsquo;il faut attribuer l&rsquo;unit\u00e9 du d\u00e9cor -inachev\u00e9- du c\u00e9l\u00e8bre ch\u00e2teau.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">L&rsquo;am\u00e9nagement des biblioth\u00e8ques trouve sa forme classique illustr\u00e9e dans l&rsquo;ouvrage consacr\u00e9 au cabinet de la biblioth\u00e8que de Sainte-Genevi\u00e8ve \u00e9tablie en 1675. Ses gravures montrent une galerie au sol carrel\u00e9 et aux parois enti\u00e8rement garnies de rayonnages int\u00e9gr\u00e9s aux boiseries, s\u00e9par\u00e9s par des pilastres. Les portes sont dissimul\u00e9es par des dos de faux livres.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Jean Le Pautre, dans une gravure intitul\u00e9e le Cabinet des Beaux-Arts, place les rayonnages de part et d&rsquo;autre d&rsquo;une table supportant une pendule et des instruments scientifiques: globes terrestres et c\u00e9lestes, aux supports tourn\u00e9s ou sculpt\u00e9s, qui font partie du mobilier de ces pi\u00e8ces.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">La richesse des formes et des mati\u00e8res des boiseries rivalise avec celle des plafonds.<br \/>Par souci d&rsquo;un confort permanent (isolation thermique, hygrom\u00e9trique, et acoustique), l&rsquo;habitude de rev\u00eatir les parois des appartements de boiseries se r\u00e9pand. En effet, le bois est un mat\u00e9riau sain dont la seule servitude est la largeur des assemblages.<br \/>Comme l&rsquo;importation de bois tendre est interrompue en 1668 par la guerre de Hollande, l&#8217;emploi du bois de ch\u00eane de France se g\u00e9n\u00e9ralise.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Suivant le testament du Cardinal, la biblioth\u00e8que am\u00e9nag\u00e9e par Le Vau en 1665 au Palais Mazarin est transf\u00e9r\u00e9e en 1672 au Coll\u00e8ge des Quatre Nations (Aujourd&rsquo;hui l&rsquo;Institut de France) o\u00f9 ses boiseries de ch\u00eane cir\u00e9 sont remont\u00e9es et sont toujours en place avec leurs rayons ourl\u00e9s de \u00ab\u00a0bougrans\u00a0\u00bb. En 1739, elle sera sur\u00e9lev\u00e9e d&rsquo;un attique avec un balcon. Elle a servi de mod\u00e8le pour la Biblioth\u00e8que royale de Copenhague.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">A Reims, la biblioth\u00e8que install\u00e9e en 1678 sous les combles au Coll\u00e8ge des J\u00e9suites a des rayonnages de ch\u00eane cir\u00e9 sous une vo\u00fbte bois\u00e9e \u00e0 caissons moulur\u00e9s de m\u00eame bois. Tables et pupitres sont install\u00e9s dans des logettes m\u00e9nag\u00e9es dans les \u00e9brasements des lucarnes.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">En 1691, Daviler \u00e9crit dans son cours: \u00ab\u00a0Les boiseries rendent les lieux secs et chauds et, par cons\u00e9quent, sains et habitables, peu de temps apr\u00e8s qu&rsquo;ils ont \u00e9t\u00e9 b\u00e2tis; outre qu&rsquo;ils \u00e9pargnent les meubles dans les pi\u00e8ces d&rsquo;une moyenne grandeur et les plus fr\u00e9quent\u00e9es, car si elles sont bois\u00e9es, il ne faut pour les meubler que quelques miroirs et tableaux qu&rsquo;on attache sur les panneaux. Les boiseries servent encore \u00e0 corriger les d\u00e9fauts dans les pi\u00e8ces comme un biais ou une enclave caus\u00e9 par quelque tuyau de chemin\u00e9e \u00e0 c\u00f4t\u00e9 duquel on pratique des armoires dont les guichets (portes) conservent la m\u00eame sym\u00e9trie que le reste.\u00a0\u00bb<br \/>Renon\u00e7ant aux fastes renouvel\u00e9s des palais antiques, le roi quinquag\u00e9naire (Louis XIV) d\u00e9cide avec Jules Hardouin-Mansart de rev\u00eatir de boiseries toutes les pi\u00e8ces des appartements du nouveau Trianon, o\u00f9 le marbre est employ\u00e9 \u00e0 l&rsquo;ext\u00e9rieur. Il fait de m\u00eame \u00e0 Marly et dans son appartement particulier de Versailles, qui est \u00ab\u00a0bois\u00e9 dans son entier.\u00a0\u00bb<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Pierre Le Pautre, publie un recueil de \u00ab\u00a0Portes \u00e0 placards et lambris dessin\u00e9es par le Sieur Mansart et nouvellement ex\u00e9cut\u00e9es dans quelques maisons royales\u00a0\u00bb, o\u00f9 l&rsquo;on voit des mod\u00e8les pour la salle de billard de Versailles (1685) et l&rsquo;antichambre de Trianon (1687). La m\u00eame disposition est employ\u00e9e dans les pi\u00e8ces de la M\u00e9nagerie, bois\u00e9e pour la jeune Duchesse de Bourgogne (1685-1712). Ce sont des boiseries, caract\u00e9ris\u00e9es par un quadrillage \u00e0 compartiments, fortement moulur\u00e9s formant saillie sur le nu des champs simplement \u00e9tag\u00e9s au-dessus de la cimaise, coup\u00e9s horizontalement par une astragale correspondant \u00e0 la partie sup\u00e9rieure du chambranle des portes.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Cependant les moulures \u00e0 forte saillie vont s&rsquo;att\u00e9nuant et l&rsquo;\u00e9chelle des sculptures diminue, c\u00e9dant la place \u00e0 des boiseries d&rsquo;un nouveau go\u00fbt, qui sont \u00e0 la fois un \u00e9l\u00e9ment de fonction et de d\u00e9coration.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">A partir de 1699, succ\u00e8de donc, une nouvelle disposition des corps de boiseries o\u00f9 les verticales sont affirm\u00e9es.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Dans les boiseries des derniers appartements du roi, tant \u00e0 Trianon qu&rsquo;\u00e0 Versailles, \u00e0 partir de 1701, les boiseries \u00e0 grands cadres, \u00e0 moulures saillantes et les astragales disparaissent et sont remplac\u00e9es par des \u00ab\u00a0boiseries de hauteur\u00a0\u00bb soumises \u00e0 une ordonnance architecturale de boiseries \u00e0 petits cadres aux moulures moins saillantes et toujours prises dans l&rsquo;\u00e9paisseur du bois: au-dessus de la boiserie d&rsquo;appui somm\u00e9e par la cimaise, de hauts panneaux verticaux, plus l\u00e9gers, s\u00e9par\u00e9s par des pilastres d&rsquo;ordre classique &#8211; qui sont bient\u00f4t remplac\u00e9s par des \u00ab\u00a0trumeaux allong\u00e9s\u00a0\u00bb- rythment les murs, divis\u00e9s en trav\u00e9es par des portes sym\u00e9triques \u00e0 deux vantaux, surmont\u00e9s par des dessus de portes peints ou sculpt\u00e9s.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Pierre Lassurance (1655-1724) et Pierre Le Pautre en donnent des mod\u00e8les o\u00f9 l&rsquo;on voit les hauts \u00ab\u00a0miroirs \u00e0 la Mansart\u00a0\u00bb plac\u00e9s au-dessus des chemin\u00e9es basses y rempla\u00e7ant les peintures. Celles-ci sont mises en dessus de portes et on y note des panneaux en rectangle dont un des petits c\u00f4t\u00e9s s&rsquo;incurve \u00e0 la rencontre de cercles. Les portes \u00e0 placards sont compos\u00e9es comme les boiseries; \u00e0 ceux-ci, Mansart donne plus de l\u00e9g\u00e8ret\u00e9 et d&rsquo;\u00e9l\u00e9gance avec des panneaux de plus grande \u00e9chelle et des compartiments destin\u00e9s \u00e0 ench\u00e2sser un assemblage de miroirs ou des peintures.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Peu apr\u00e8s, \u00e0 Trianon-sous-Bois, on voit l&rsquo;apparition de hauts pilastres et les cl\u00e9s des arcades des chambranles et des cadres de glace y sont orn\u00e9s d&rsquo;une palmette. Cette mani\u00e8re de disposer les boiseries donne une l\u00e9g\u00e8ret\u00e9 nouvelle \u00e0 la d\u00e9coration et fournit un premier exemple des boiseries typiques du dix-huiti\u00e8me si\u00e8cle.<br \/>Il est \u00e0 remarquer que les boiseries basses sont surmont\u00e9es par la moulure saillante de la cimaise, g\u00e9n\u00e9ralement plac\u00e9e \u00e0 deux pieds huit pouces (1) du sol (soit 0,86 m de hauteur d&rsquo;appui) destin\u00e9e \u00e0 arr\u00eater le dossier des si\u00e8ges, toujours align\u00e9s sym\u00e9triquement contre les murs et \u00e0 r\u00e9gner avec les dessus de marbre des tables en consoles et des commodes (celles-ci plac\u00e9es dans les chambres).<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Dans les pi\u00e8ces moins richement d\u00e9cor\u00e9es on se contente de peindre les boiseries en \u00ab\u00a0marbre contrefait\u00a0\u00bb ou \u00ab\u00a0marbre feint\u00a0\u00bb, comme aux salons des ch\u00e2teaux de Vaux-le-Vicomte et de Balleroy et \u00e0 l&rsquo;h\u00f4tel de Chatillon, \u00e0 Paris; de m\u00eame dans les pi\u00e8ces de moindre cons\u00e9quence, comme les antichambres ou la salle-\u00e0-manger avec des \u00ab\u00a0boiseries peintes en marbre\u00a0\u00bb (chez Monsieur B\u00e9gon).<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">L&rsquo;harmonie du blanc relev\u00e9 d&rsquo;or semble avoir plu \u00e0 Louis XIV (il s&rsquo;agit toujours de dorure \u00e0 l&rsquo;eau et non \u00e0 l&rsquo;huile). A Trianon les boiseries d&rsquo;apparat sont peintes \u00e0 la d\u00e9trempe \u00ab\u00a0blanc de roi\u00a0\u00bb et la sculpture est soigneusement pr\u00e9par\u00e9e pour recevoir les feuilles d&rsquo;or.<br \/>Mais les boiseries des logements des grands officiers sont laiss\u00e9es en bois naturel.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Et Jean-Baptiste Leroux dans ses \u00ab\u00a0Nouveaux lambris de galeries, chambres et cabinets\u00a0\u00bb (1700), montre une biblioth\u00e8que de ch\u00eane naturel et or.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Cette mode, en \u00ab\u00a0Blanc de roi\u00a0\u00bb, provoque la plainte d&rsquo;un esprit chagrin: \u00ab\u00a0Dans les appartements de parade l&#8217;emploi de la dorure flatte les parvenus et ruine la noblesse. Par contre, dans les parties telles les passages et antichambres ce n&rsquo;est pas le cas\u00a0\u00bb.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Certains sp\u00e9cialistes comme Daviler veulent \u00ab\u00a0garder au bois des lambris sa couleur naturelle\u00a0\u00bb.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">C&rsquo;est l&rsquo;avis de l&rsquo;architectes Boffrand qui \u00e9crit: \u00ab\u00a0On peut vernir la boiserie, en sorte qu&rsquo;on y voit la couleur du bois\u00a0\u00bb<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">La p\u00e9nurie financi\u00e8re due \u00e0 la guerre de la succession d&rsquo;Espagne arr\u00eate les travaux, et, boiseries et corniches restent en blanc, car un \u00e9dit de 1691 interdit la dorure. Ce qui n&#8217;emp\u00eache pas deux traitants Beauvarlais et Antoine Crozat, de l&rsquo;enfreindre dans la d\u00e9coration de leurs h\u00f4tels place Vend\u00f4me.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Apr\u00e8s l&rsquo;\u00e9dit de 1691, on voit appara\u00eetre \u00e0 nouveau des boiseries en bois naturel, simplement cir\u00e9es, Ce qui correspond au souhait de Jacques Fran\u00e7ois Blondel: \u00ab\u00a0pour l&rsquo;amour du vrai, que les boiseries de ch\u00eane fussent seulement cir\u00e9es\u00a0\u00bb.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Nicod\u00e8me Tessin \u00e9crit en 1693: \u00a0\u00bb On ne peint les chambres bois\u00e9es, les portes, les volets, les ch\u00e2ssis, les plafonds, etc&#8230; que de blanc, avec le filet d&rsquo;or, ou sans or\u00a0\u00bb. Lorsque les travaux reprennent en 1698, le roi donne l&rsquo;ordre de m\u00e9nager l&rsquo;or sur les boiseries et la dorure s&rsquo;y r\u00e9duit aux moulures des bordures des glaces et de celles des tableaux, ainsi que sur les pieds des tables en consoles des trumeaux. A Trianon comme \u00e0 Marly, ce qui diff\u00e9rencie alors les pi\u00e8ces des appartements, tous peints en blanc du Roi, ce sont les emmeublements chacun d&rsquo;une couleur diff\u00e9rente.<br \/>Les portes \u00e0 panneaux simplement moulur\u00e9s remplacent les vantaux charg\u00e9s de sculptures en bas-relief.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Chez les particuliers, si l&rsquo;on r\u00e9serve le blanc et or pour le cabinet \u00ab\u00a0lorsqu&rsquo;on est en \u00e9tat de soutenir la d\u00e9pense\u00a0\u00bb, \u00e0 certains moments, pour unifier les tons des diff\u00e9rentes sortes de bois et masquer les d\u00e9fauts (noeuds, etc&#8230;), on vernit le reste des boiseries, \u00ab\u00a0\u00e0 la capucine\u00a0\u00bb, c&rsquo;est-\u00e0-dire qu&rsquo;on les peint en faux bois du ton de la bure des Capucins (Franciscains). Exemple: la pharmacie des Invalides 1707. Malgr\u00e9 les objections de Blondel.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">\u00ab\u00a0Les pi\u00e8ces consacr\u00e9es \u00e0 la lecture doivent avoir un air de simplicit\u00e9 pour plus de recueillement\u00a0\u00bb Si le nombre des livres est tr\u00e8s important, les biblioth\u00e8ques peuvent quelquefois \u00eatre install\u00e9es sur deux \u00e9tages, avec un balcon, comme au ch\u00e2teau de Brienne (Aube), et de la Roche-Guyon (Val d&rsquo;Oise), mais ce sont g\u00e9n\u00e9ralement des pi\u00e8ces intimes \u00ab\u00a0pour jouir de l&rsquo;agr\u00e9ment de la lecture\u00a0\u00bb, lambriss\u00e9es avec des armoires de boiserie aux portes grillag\u00e9es prot\u00e9geant les ouvrages contre le vol, dans des contours chantourn\u00e9s. Le corps bas correspond aux boiseries d&rsquo;appui. Le long des \u00e9tag\u00e8res on peut mettre des \u00ab\u00a0bougrans\u00a0\u00bb ou canevas, accommod\u00e9s \u00e0 clous dor\u00e9s destin\u00e9s \u00e0 \u00ab\u00a0conserver les livres de la poudre\u00a0\u00bb. Les portes peuvent \u00eatre dissimul\u00e9es par des rayonnages feints et des dos de livres en cuir.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Dans les cabinets entresol\u00e9s, les corps de biblioth\u00e8ques sont couronn\u00e9s par une corniche qui touche au plafond. Dans les pi\u00e8ces \u00e9lev\u00e9es le haut des armoires de menuiserie ou d&rsquo;\u00e9b\u00e9nisterie est orn\u00e9 de bustes, de vases ou de groupes sculpt\u00e9s (comme au Palais Rohan \u00e0 Strasbourg).<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Architectes et ornementalistes en proposent de nombreux projets: Robert de Cotte pour l&rsquo;h\u00f4tel de Nevers, Nicolas Pineau pour M. de Rouill\u00e9. Certains sont grav\u00e9s par Pierre le Pautre, les Bonnard, etc. Une gravure de Jean Mariette repr\u00e9sente une \u00ab\u00a0boiserie de cabinet avec biblioth\u00e8que de ch\u00eane verni; les ornements en sont dor\u00e9s et appliqu\u00e9s sur le bois\u00a0\u00bb.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Si les travaux de Henri Labrouste (1801-1875) ont fait dispara\u00eetre les boiseries de la biblioth\u00e8que royale install\u00e9e dans l&rsquo;H\u00f4tel de Nevers \u00e0 partir de 1721, on retrouve des panneaux en bois naturels remont\u00e9s dans l&rsquo;ancien h\u00f4tel B\u00e9hague \u00e0 Paris (aujourd&rsquo;hui Ambassade de Roumanie).<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Pour acc\u00e9der aux rayons sup\u00e9rieurs, les menuisiers ex\u00e9cutent des escaliers mobiles.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">D\u00e9sormais, salons de compagnie et salles d&rsquo;assembl\u00e9e, comme les autres pi\u00e8ces des appartements nouveaux, sont tous pourvus de boiseries qui assurent l&rsquo;isolation thermique et acoustique et l&rsquo;harmonie d&rsquo;une architecture int\u00e9rieure de panneaux de boiserie bien distribu\u00e9s selon une \u00ab\u00a0sym\u00e9trie raisonnable et r\u00e9fl\u00e9chie\u00a0\u00bb (Jacques Fran\u00e7ois Blondel). Dans le texte de 1738 du cours de Daviler, on lit: \u00ab\u00a0La d\u00e9coration int\u00e9rieure des appartements a \u00e9prouv\u00e9 de si grands changements qu&rsquo;elle a tout fait changer de face&#8230; Les boiseries que l&rsquo;on fait pr\u00e9sentement sont si diff\u00e9rentes de celles qui \u00e9taient en usage il y a quelques ann\u00e9es qu&rsquo;on a trouv\u00e9 \u00e0 propos d&rsquo;en donner de nouveaux dessins\u00a0\u00bb.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Oeuvres de grands sp\u00e9cialistes en menuiserie d&rsquo;art, les boiseries de grande qualit\u00e9 sont toujours ex\u00e9cut\u00e9es en bois dur, notamment en ch\u00eane, mat\u00e9riau r\u00e9put\u00e9 sain. Ils sont faits de \u00ab\u00a0ch\u00eane propre et sans noeud, bien sec\u00a0\u00bb (\u00e0 l&rsquo;air), c&rsquo;est-\u00e0-dire qui n&rsquo;est pas parvenu par flottage, ce qui en augmente le prix. Toutes les moulures et ornements en relief y sont sculpt\u00e9s en plein bois.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Dans les salles par\u00e9es de boiseries, les murs sont trait\u00e9s comme un ordre d&rsquo;architecture: cet ordre repose sur un stylobate: la boiserie d&rsquo;appui mesure g\u00e9n\u00e9ralement deux pieds huit pouces, cependant, Boffrans, pour accentuer l&rsquo;\u00e9l\u00e9vation de certaines pi\u00e8ces donne quelquefois aux boiseries basses moins de huit pouces, hauteur d\u00e9sormais traditionnelle dans les B\u00e2timents du roi et les h\u00f4tels parisiens.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Toujours harmonieusement distribu\u00e9s, les ornements sculpt\u00e9s des boiseries et des voussures qui les prolongent sont multipli\u00e9s dans les appartements de parade, ce qui fait dire \u00e0 Pierre Patte en 1775, dans son cours d&rsquo;architecture: \u00ab\u00a0La sculpture s&rsquo;\u00e9tait enti\u00e8rement rendue ma\u00eetresse de l&rsquo;architecture\u00a0\u00bb.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Le plus souvent cependant, la hauteur de la boiserie d&rsquo;appui est r\u00e9gl\u00e9e par l&rsquo;\u00e9l\u00e9vation de la pi\u00e8ce\u00a0\u00bb (Briseux recommande de donner \u00e0 la hauteur sous plafond les trois cinqui\u00e8me de la largeur de la pi\u00e8ce). Dans les pi\u00e8ces tr\u00e8s hautes mesurant plus de dix-huit pieds (5,83 m) d&rsquo;\u00e9l\u00e9vation, la boiserie d&rsquo;appui peut atteindre trois pieds (0,97 m). Cette boiserie basse, divis\u00e9e en panneaux, de largeur vari\u00e9e, sans d\u00e9cor sculpt\u00e9, est limit\u00e9e au sol par la plinthe ou socle de boiserie reposant sur le plancher. On donne \u00e0 la plinthe une hauteur de quatre pouces (10,8 cm) environ.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">En haut des boiseries d&rsquo;appui se trouve le ressaut de la cimaise, moulure saillante contre laquelle viennent s&rsquo;appuyer les meubles; si\u00e8ges meublants (canap\u00e9s et fauteuils) toujours align\u00e9s contre les murs. Jacques Fran\u00e7ois Blondel insiste: \u00a0\u00bb On doit prendre garde que les contours inf\u00e9rieurs des panneaux ne tombent point assez bas pour que les dossiers des fauteuils puissent en d\u00e9rober la vue.\u00a0\u00bb<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Pour les boiserie de hauteur, au-dessus de la boiserie d&rsquo;appui, le rythme vertical est marqu\u00e9 par des pilastres et\/ou des panneaux \u00e9troits (parcloses) entre lesquels viennent s&#8217;embrever des corps plus larges, soulign\u00e9s de moulures, d\u00e9cor\u00e9s de motifs sculpt\u00e9s en bas relief \u00ab\u00a0le plus l\u00e9ger qu&rsquo;il soit possible\u00a0\u00bb (Jean Mariette), \u00e0 moins qu&rsquo;on y ins\u00e8re des toiles peintes, des glaces ou encore des panneaux de laque, par exemple les toiles par Christophe Huet dans la chambre du prince \u00e0 Chantilly, les glaces de la galerie de l&rsquo;h\u00f4tel de Villars et du salon de l&rsquo;h\u00f4tel de Soyecourt par Nicolas Pineau \u00e0 Paris. Les divisions g\u00e9om\u00e9triques des boiseries sont toujours claires: les verticales encadrent une surface, qui s&rsquo;organise selon une sym\u00e9trie. On ne redouble pas forc\u00e9ment les pilastres dans les coins.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Les portes, sont souvent \u00e9quilibr\u00e9es par un panneau plein et non par une porte simul\u00e9e. \u00ab\u00a0Il y a des architectes qui, dans la d\u00e9coration des appartements, ont coutume de r\u00e9p\u00e9ter des portes feintes en sym\u00e9trie ou \u00e0 l&rsquo;opposition des vraies pour les grandir en apparence, d&rsquo;o\u00f9 il r\u00e9sulte que dans les pi\u00e8ces o\u00f9 l&rsquo;on est dans l&rsquo;obligation d&rsquo;avoir beaucoup de si\u00e8ges, on est contraint d&rsquo;en mettre devant ces portes, ce qui ne para\u00eet pas naturel.\u00a0\u00bb<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Surmont\u00e9es soit de toiles peintes ench\u00e2ss\u00e9es dans des moulures, soit de panneaux sculpt\u00e9s d&rsquo;ornements en bas relief, les portes des pi\u00e8ces de r\u00e9ception affleurent le mur, s&rsquo;ouvrent \u00e0 deux vantaux vers les pi\u00e8ces secondaires et sont doubl\u00e9es par des rideaux de porti\u00e8re de tissu en hiver.<br \/>Des portes d\u00e9rob\u00e9es, \u00e0 un seul vantail, peuvent \u00eatre d\u00e9coup\u00e9es dans les boiseries en tenant compte du d\u00e9cor.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Pour juger de l&rsquo;effet du d\u00e9cor des boiseries pr\u00e9vues dans une pi\u00e8ce, on en trace souvent une esquisse, \u00e0 grandeur d&rsquo;ex\u00e9cution, \u00e0 la pierre noire, directement sur le pl\u00e2tre du mur, qui est parfois retrouv\u00e9e lors de la d\u00e9pose des boiseries, ou bien cette esquisse est trac\u00e9e sur un papier ou un tissu afin d&rsquo;\u00eatre pr\u00e9sent\u00e9e sur le mur.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Dans les \u00ab\u00a0petits appartements\u00a0\u00bb, les boiseries de hauteur sont \u00e9tablies en proportion de la hauteur sous plafond. Par exemple, \u00e0 Versailles, dans les cabinets install\u00e9s par Louis XV sous les combles, on trouve des pi\u00e8ces ayant huit pieds neuf pouces de hauteur (2,83 m) o\u00f9 les boiseries mesurent huit pieds quatre pouces (2,73 m) surmont\u00e9es d&rsquo;une corniche en voussure de quatre pouces (0,10 m). La boiserie basse y monte \u00e0 deux pieds cinq pouces seulement (0,78 m) et la chemin\u00e9e \u00e0 environ trois pieds quatre pouces (1,07 m) Pour pallier le manque de hauteur on multiplie le nombre des lignes montantes en augmentant le nombre des panneaux verticaux \u00e9troits, le d\u00e9cor sculpt\u00e9 de la corniche vient mordre sur le plafond o\u00f9 l&rsquo;on ne met pas de rosace centrale.<br \/>La largeur des panneaux mis en oeuvre est limit\u00e9e par les assemblages \u00e0 cause des variations dimensionnelles dues aux variations hygrom\u00e9trique qui se risque de se voir au niveau des embr\u00e8vements (\u00e0 trois pieds de largeur comme le conseille Roubot).<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">On con\u00e7oit que dans des pi\u00e8ces ainsi par\u00e9es de boiseries, orn\u00e9es de sculptures et de miroirs, il y ait peu de place pour les tr\u00e8s grands tableaux de peinture. Ceux-ci sont parfois ench\u00e2ss\u00e9s dans la boiserie et ne prennent vraiment leur sens qu&rsquo;int\u00e9gr\u00e9s dans le d\u00e9cor entier comme \u00e0 la petite galerie des chasses exotiques \u00e0 Versailles (d\u00e9truite, les toiles \u00e9tant au mus\u00e9e d&rsquo;Amiens). Ils sont aussi plac\u00e9s au-dessus des portes. On dispose aussi des tableaux en partie haute des trumeaux des glaces, ce qui provoque la critique d&rsquo;un anonyme en 1753 du \u00ab\u00a0go\u00fbt barbare qui a banni les tableaux des appartements pour leur substitution par d&rsquo;insipides glaces qui ne permet \u00e0 la peinture tout au plus que d&rsquo;ex\u00e9cuter quelques bizarrerie sur les dessus de portes\u00a0\u00bb (Jugement d&rsquo;un amateur sur l&rsquo;exposition de tableaux).<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Les variations de la mode, ont \u00e9t\u00e9 la cause du renouvellement cyclique de la finition des boiseries dans les appartements. Ces travaux expliquent que pratiquement aucune boiserie ne nous soit parvenue dans sa finition d&rsquo;origine.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Pour proc\u00e9der au rajeunissement des boiseries, souvent on les enduit d&rsquo;une couche de peinture, apr\u00e8s quelque temps d&rsquo;une autre, aboutissant \u00e0 un emp\u00e2tement des reliefs; Puis \u00e0 d&rsquo;autres p\u00e9riodes, on proc\u00e8de \u00e0 un d\u00e9capage g\u00e9n\u00e9ral, par application d&rsquo;un solvant, par un d\u00e9collement \u00e0 la flamme ou par un grattage \u00e0 vif, pour d\u00e9gorger les ornements sculpt\u00e9s, r\u00e9v\u00e9lant ainsi le bois dans sa couleur naturelle.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Quoi qu&rsquo;il en soit, le dix-huiti\u00e8<\/span><\/b><span style=\"font-size: medium;\"><b>me si\u00e8cle aura \u00e9t\u00e9 l&rsquo;apog\u00e9e du savoir faire des \u00e9b\u00e9nistes &#8211; menuisiers d&rsquo;art en ce qui concerne les boiseries (entre autres).<\/b><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">Jamais aucune autre \u00e9poque n&rsquo;a su cr\u00e9er des rythmes ni des rapports de proportions aussi agr\u00e9ables malgr\u00e9 tout ce qui a pu \u00eatre d\u00e9couvert depuis cette p\u00e9riode.<\/span><\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><b><span style=\"font-size: medium;\">(1) 1 pouce fran\u00e7ais = 27,0696 mm<\/span><\/b><\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au moyen \u00e2ge \u00e0 la fin du seizi\u00e8me si\u00e8cle, dans les pi\u00e8ces o\u00f9 les habitants vivent avec leurs animaux familiers, les sols doivent pouvoir \u00eatre lav\u00e9s \u00e0 grande eau. Aussi les grandes salles vo\u00fbt\u00e9es des ch\u00e2teaux (salle des gardes, salles des festins ou \u00ab\u00a0grand tinel\u00a0\u00bb), sont-elles g\u00e9n\u00e9ralement dall\u00e9es de pierre.ALes planchers de bois sont r\u00e9serv\u00e9s [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[6],"tags":[],"class_list":["post-121","post","type-post","status-publish","format-standard","hentry","category-ebenisterie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Planchers et parquets - Maison Pingeon depuis 1841<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/pingeon.com\/index.php\/2023\/02\/06\/planchers-et-parquets\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Planchers et parquets - Maison Pingeon depuis 1841\" \/>\n<meta property=\"og:description\" content=\"Au moyen \u00e2ge \u00e0 la fin du seizi\u00e8me si\u00e8cle, dans les pi\u00e8ces o\u00f9 les habitants vivent avec leurs animaux familiers, les sols doivent pouvoir \u00eatre lav\u00e9s \u00e0 grande eau. Aussi les grandes salles vo\u00fbt\u00e9es des ch\u00e2teaux (salle des gardes, salles des festins ou &quot;grand tinel&quot;), sont-elles g\u00e9n\u00e9ralement dall\u00e9es de pierre.ALes planchers de bois sont r\u00e9serv\u00e9s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/pingeon.com\/index.php\/2023\/02\/06\/planchers-et-parquets\/\" \/>\n<meta property=\"og:site_name\" content=\"Maison Pingeon depuis 1841\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-06T19:16:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-06T19:29:11+00:00\" \/>\n<meta name=\"author\" content=\"val\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"val\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"29 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/pingeon.com\\\/index.php\\\/2023\\\/02\\\/06\\\/planchers-et-parquets\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/pingeon.com\\\/index.php\\\/2023\\\/02\\\/06\\\/planchers-et-parquets\\\/\"},\"author\":{\"name\":\"val\",\"@id\":\"http:\\\/\\\/pingeon.com\\\/#\\\/schema\\\/person\\\/94f30a53f85b874d07e82a456da42d0a\"},\"headline\":\"Planchers et parquets\",\"datePublished\":\"2023-02-06T19:16:38+00:00\",\"dateModified\":\"2023-02-06T19:29:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/pingeon.com\\\/index.php\\\/2023\\\/02\\\/06\\\/planchers-et-parquets\\\/\"},\"wordCount\":6043,\"publisher\":{\"@id\":\"http:\\\/\\\/pingeon.com\\\/#organization\"},\"articleSection\":[\"Eb\u00e9nisterie\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/pingeon.com\\\/index.php\\\/2023\\\/02\\\/06\\\/planchers-et-parquets\\\/\",\"url\":\"http:\\\/\\\/pingeon.com\\\/index.php\\\/2023\\\/02\\\/06\\\/planchers-et-parquets\\\/\",\"name\":\"Planchers et parquets - Maison Pingeon depuis 1841\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/pingeon.com\\\/#website\"},\"datePublished\":\"2023-02-06T19:16:38+00:00\",\"dateModified\":\"2023-02-06T19:29:11+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/pingeon.com\\\/index.php\\\/2023\\\/02\\\/06\\\/planchers-et-parquets\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/pingeon.com\\\/index.php\\\/2023\\\/02\\\/06\\\/planchers-et-parquets\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/pingeon.com\\\/index.php\\\/2023\\\/02\\\/06\\\/planchers-et-parquets\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"http:\\\/\\\/pingeon.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Planchers et parquets\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/pingeon.com\\\/#website\",\"url\":\"http:\\\/\\\/pingeon.com\\\/\",\"name\":\"Maison Pingeon depuis 1841\",\"description\":\"Boiserie d&#039;art\",\"publisher\":{\"@id\":\"http:\\\/\\\/pingeon.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/pingeon.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/pingeon.com\\\/#organization\",\"name\":\"Eb\u00e9nisterie d'Art et boiseries anciennes\",\"url\":\"http:\\\/\\\/pingeon.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\\\/\\\/pingeon.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/pingeon.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/logo_20230108_174658-1.png\",\"contentUrl\":\"http:\\\/\\\/pingeon.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/logo_20230108_174658-1.png\",\"width\":852,\"height\":872,\"caption\":\"Eb\u00e9nisterie d'Art et boiseries anciennes\"},\"image\":{\"@id\":\"http:\\\/\\\/pingeon.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/pingeon.com\\\/#\\\/schema\\\/person\\\/94f30a53f85b874d07e82a456da42d0a\",\"name\":\"val\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bd5e695cdf60df72fb4b940e1d8696a034d71ede758647ffbe9643f8903fdb86?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bd5e695cdf60df72fb4b940e1d8696a034d71ede758647ffbe9643f8903fdb86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bd5e695cdf60df72fb4b940e1d8696a034d71ede758647ffbe9643f8903fdb86?s=96&d=mm&r=g\",\"caption\":\"val\"},\"url\":\"https:\\\/\\\/pingeon.com\\\/index.php\\\/author\\\/val\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Planchers et parquets - Maison Pingeon depuis 1841","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/pingeon.com\/index.php\/2023\/02\/06\/planchers-et-parquets\/","og_locale":"fr_FR","og_type":"article","og_title":"Planchers et parquets - Maison Pingeon depuis 1841","og_description":"Au moyen \u00e2ge \u00e0 la fin du seizi\u00e8me si\u00e8cle, dans les pi\u00e8ces o\u00f9 les habitants vivent avec leurs animaux familiers, les sols doivent pouvoir \u00eatre lav\u00e9s \u00e0 grande eau. Aussi les grandes salles vo\u00fbt\u00e9es des ch\u00e2teaux (salle des gardes, salles des festins ou \"grand tinel\"), sont-elles g\u00e9n\u00e9ralement dall\u00e9es de pierre.ALes planchers de bois sont r\u00e9serv\u00e9s [&hellip;]","og_url":"http:\/\/pingeon.com\/index.php\/2023\/02\/06\/planchers-et-parquets\/","og_site_name":"Maison Pingeon depuis 1841","article_published_time":"2023-02-06T19:16:38+00:00","article_modified_time":"2023-02-06T19:29:11+00:00","author":"val","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"val","Dur\u00e9e de lecture estim\u00e9e":"29 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/pingeon.com\/index.php\/2023\/02\/06\/planchers-et-parquets\/#article","isPartOf":{"@id":"http:\/\/pingeon.com\/index.php\/2023\/02\/06\/planchers-et-parquets\/"},"author":{"name":"val","@id":"http:\/\/pingeon.com\/#\/schema\/person\/94f30a53f85b874d07e82a456da42d0a"},"headline":"Planchers et parquets","datePublished":"2023-02-06T19:16:38+00:00","dateModified":"2023-02-06T19:29:11+00:00","mainEntityOfPage":{"@id":"http:\/\/pingeon.com\/index.php\/2023\/02\/06\/planchers-et-parquets\/"},"wordCount":6043,"publisher":{"@id":"http:\/\/pingeon.com\/#organization"},"articleSection":["Eb\u00e9nisterie"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"http:\/\/pingeon.com\/index.php\/2023\/02\/06\/planchers-et-parquets\/","url":"http:\/\/pingeon.com\/index.php\/2023\/02\/06\/planchers-et-parquets\/","name":"Planchers et parquets - Maison Pingeon depuis 1841","isPartOf":{"@id":"http:\/\/pingeon.com\/#website"},"datePublished":"2023-02-06T19:16:38+00:00","dateModified":"2023-02-06T19:29:11+00:00","breadcrumb":{"@id":"http:\/\/pingeon.com\/index.php\/2023\/02\/06\/planchers-et-parquets\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/pingeon.com\/index.php\/2023\/02\/06\/planchers-et-parquets\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/pingeon.com\/index.php\/2023\/02\/06\/planchers-et-parquets\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"http:\/\/pingeon.com\/"},{"@type":"ListItem","position":2,"name":"Planchers et parquets"}]},{"@type":"WebSite","@id":"http:\/\/pingeon.com\/#website","url":"http:\/\/pingeon.com\/","name":"Maison Pingeon depuis 1841","description":"Boiserie d&#039;art","publisher":{"@id":"http:\/\/pingeon.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/pingeon.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"http:\/\/pingeon.com\/#organization","name":"Eb\u00e9nisterie d'Art et boiseries anciennes","url":"http:\/\/pingeon.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/pingeon.com\/#\/schema\/logo\/image\/","url":"http:\/\/pingeon.com\/wp-content\/uploads\/2023\/02\/logo_20230108_174658-1.png","contentUrl":"http:\/\/pingeon.com\/wp-content\/uploads\/2023\/02\/logo_20230108_174658-1.png","width":852,"height":872,"caption":"Eb\u00e9nisterie d'Art et boiseries anciennes"},"image":{"@id":"http:\/\/pingeon.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/pingeon.com\/#\/schema\/person\/94f30a53f85b874d07e82a456da42d0a","name":"val","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/bd5e695cdf60df72fb4b940e1d8696a034d71ede758647ffbe9643f8903fdb86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bd5e695cdf60df72fb4b940e1d8696a034d71ede758647ffbe9643f8903fdb86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bd5e695cdf60df72fb4b940e1d8696a034d71ede758647ffbe9643f8903fdb86?s=96&d=mm&r=g","caption":"val"},"url":"https:\/\/pingeon.com\/index.php\/author\/val\/"}]}},"_links":{"self":[{"href":"https:\/\/pingeon.com\/index.php\/wp-json\/wp\/v2\/posts\/121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pingeon.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pingeon.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pingeon.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/pingeon.com\/index.php\/wp-json\/wp\/v2\/comments?post=121"}],"version-history":[{"count":2,"href":"https:\/\/pingeon.com\/index.php\/wp-json\/wp\/v2\/posts\/121\/revisions"}],"predecessor-version":[{"id":124,"href":"https:\/\/pingeon.com\/index.php\/wp-json\/wp\/v2\/posts\/121\/revisions\/124"}],"wp:attachment":[{"href":"https:\/\/pingeon.com\/index.php\/wp-json\/wp\/v2\/media?parent=121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pingeon.com\/index.php\/wp-json\/wp\/v2\/categories?post=121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pingeon.com\/index.php\/wp-json\/wp\/v2\/tags?post=121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}